{"id":764,"date":"2025-10-21T16:10:42","date_gmt":"2025-10-21T16:10:42","guid":{"rendered":"https:\/\/wearin.tech\/?page_id=764"},"modified":"2025-11-05T13:28:18","modified_gmt":"2025-11-05T13:28:18","slug":"terms-and-conditions","status":"publish","type":"page","link":"https:\/\/wearin.tech\/fr\/terms-and-conditions\/","title":{"rendered":"Conditions g\u00e9n\u00e9rales d'utilisation"},"content":{"rendered":"<section class=\"page-hero2-section\" style=\"background-image: url(https:\/\/wearin.tech\/wp-content\/uploads\/2025\/11\/header_static_2560x1440_Partners-2.webp);\">\r\n        <div class=\"container\">\r\n        <div class=\"row align-items-end half-height\">\r\n            <div class=\"col-lg-10\">\r\n                <div class=\"section-title\"><h1>Conditions g\u00e9n\u00e9rales d'utilisation<\/h1><\/div>            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/section>\n\n<section class=\"content-single-section\">\r\n    <div class=\"container\">\r\n        <div class=\"row justify-content-center\">\r\n            <div class=\"col-lg-8\"><div class=\"text-block\"><div class=\"container fade-in-top\">\n<div>\n<h4 class=\"content-title-color-var\">1. Introduction<\/h4>\n<p>&nbsp;<\/p>\n<p>Les pr\u00e9sentes conditions d'utilisation r\u00e9gissent votre utilisation de nos sites web.<\/p>\n<p>En utilisant notre site web, vous acceptez ces conditions dans leur int\u00e9gralit\u00e9 ; par cons\u00e9quent, si vous n'\u00eates pas d'accord avec tout ou partie de ces conditions, vous ne devez pas utiliser nos sites web.<\/p>\n<p>Nos sites web utilisent des cookies ; en utilisant nos sites web ou en acceptant les pr\u00e9sentes conditions g\u00e9n\u00e9rales, vous consentez \u00e0 ce que nous utilisions des cookies conform\u00e9ment aux conditions de notre politique en mati\u00e8re de cookies.\u00a0<a href=\"https:\/\/fischerconnectors.com\/en\/privacy-statement\/\">politique de confidentialit\u00e9<\/a>\u00a0et\u00a0<a href=\"https:\/\/fischerconnectors.com\/en\/cookies-policy\/\">politique en mati\u00e8re de cookies<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"container fade-in-top\">\n<div>\n<h4 class=\"content-title-color-var\">2. Avis de droit d'auteur<\/h4>\n<p>&nbsp;<\/p>\n<p>Copyright (c) 2018, Fischer Connectors SA<\/p>\n<p>Sous r\u00e9serve des dispositions expresses des pr\u00e9sentes conditions d'utilisation :<\/p>\n<ol>\n<li>\n<ol>\n<li>nous, ainsi que nos conc\u00e9dants, d\u00e9tenons et contr\u00f4lons tous les droits d'auteur et autres droits de propri\u00e9t\u00e9 intellectuelle de notre site web et du mat\u00e9riel qui y figure ; et<\/li>\n<li>tous les droits d'auteur et autres droits de propri\u00e9t\u00e9 intellectuelle relatifs \u00e0 notre site web et \u00e0 son contenu sont r\u00e9serv\u00e9s.<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"container fade-in-top\">\n<div>\n<h4 class=\"content-title-color-var\">3. Licence d'utilisation du site web<\/h4>\n<p>&nbsp;<\/p>\n<p>Vous pouvez :<\/p>\n<ol>\n<li>\n<ol start=\"1\">\n<li>consulter les pages de nos sites web dans un navigateur web ;<\/li>\n<li>t\u00e9l\u00e9charger des pages de nos sites web pour les mettre en cache dans un navigateur web ;<\/li>\n<li>imprimer des pages de nos sites web ;<\/li>\n<li>diffuser des fichiers audio et vid\u00e9o \u00e0 partir de nos sites web ; et<\/li>\n<li>utiliser les services de nos sites web au moyen d'un navigateur web, sous r\u00e9serve des autres dispositions des pr\u00e9sentes conditions g\u00e9n\u00e9rales.<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p>Sauf autorisation expresse des pr\u00e9sentes conditions g\u00e9n\u00e9rales, vous ne devez pas \u00e9diter ou modifier de quelque mani\u00e8re que ce soit le contenu de nos sites web.<\/p>\n<p>Nous nous r\u00e9servons le droit de restreindre l'acc\u00e8s \u00e0 certaines parties de nos sites web, voire \u00e0 l'ensemble de nos sites web, \u00e0 notre discr\u00e9tion ; vous ne devez pas contourner, ni essayer de contourner, ni tenter de contourner les mesures de restriction d'acc\u00e8s de nos sites web.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"container fade-in-top\">\n<div>\n<h4 class=\"content-title-color-var\">4. Utilisation acceptable<\/h4>\n<p>&nbsp;<\/p>\n<p>Vous ne devez pas :<\/p>\n<ol>\n<li>\n<ol start=\"1\">\n<li>utiliser nos sites web de quelque mani\u00e8re que ce soit ou prendre des mesures qui causent ou peuvent causer des dommages au site web ou une atteinte aux performances, \u00e0 la disponibilit\u00e9 ou \u00e0 l'accessibilit\u00e9 des sites web ;<\/li>\n<li>utiliser nos sites web d'une mani\u00e8re ill\u00e9gale, illicite, frauduleuse ou pr\u00e9judiciable, ou dans le cadre d'une activit\u00e9 ou d'un objectif ill\u00e9gal, illicite, frauduleux ou pr\u00e9judiciable ;<\/li>\n<li>utiliser nos sites web pour copier, stocker, h\u00e9berger, transmettre, envoyer, utiliser, publier ou distribuer tout mat\u00e9riel qui consiste en (ou est li\u00e9 \u00e0) un logiciel espion, un virus informatique, un cheval de Troie, un ver, un enregistreur de frappe, un rootkit ou tout autre logiciel informatique malveillant ;<\/li>\n<li>mener des activit\u00e9s de collecte de donn\u00e9es syst\u00e9matiques ou automatis\u00e9es (y compris, mais sans s'y limiter, le scraping, le data mining, l'extraction de donn\u00e9es et la r\u00e9colte de donn\u00e9es) sur ou en relation avec nos sites web sans notre consentement \u00e9crit expr\u00e8s ;<\/li>\n<li>acc\u00e9der \u00e0 nos sites web ou interagir avec eux de quelque mani\u00e8re que ce soit \u00e0 l'aide d'un robot, d'une araign\u00e9e ou de tout autre moyen automatis\u00e9, sauf \u00e0 des fins d'indexation par les moteurs de recherche ;<\/li>\n<li>violer les directives \u00e9nonc\u00e9es dans le fichier robots.txt de nos sites web ; ou<\/li>\n<li>utiliser les donn\u00e9es collect\u00e9es sur nos sites web pour toute activit\u00e9 de marketing direct (y compris, mais sans s'y limiter, le marketing par courrier \u00e9lectronique, le marketing par SMS, le t\u00e9l\u00e9marketing et le publipostage).<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p>Vous devez vous assurer que toutes les informations que vous nous fournissez par l'interm\u00e9diaire de nos sites web, ou en relation avec nos sites web, sont vraies, exactes, actuelles, compl\u00e8tes et non trompeuses.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"container fade-in-top\">\n<div>\n<h4 class=\"content-title-color-var\">5. Enregistrement et comptes<\/h4>\n<p>&nbsp;<\/p>\n<p>Vous pouvez cr\u00e9er un compte sur notre site web (www.fischerconnectors.com) en remplissant et en envoyant le formulaire d'enregistrement de compte sur notre site web, et en cliquant sur le lien de v\u00e9rification dans l'e-mail que le site web vous enverra. La cr\u00e9ation de ce compte est r\u00e9serv\u00e9e aux employ\u00e9s de Fischer Connectors et \u00e0 certains de ses partenaires.<\/p>\n<p>Vous ne devez pas permettre \u00e0 une autre personne d'utiliser votre compte pour acc\u00e9der \u00e0 notre site web institutionnel.<\/p>\n<p>Vous devez nous informer imm\u00e9diatement par \u00e9crit si vous avez connaissance d'une utilisation non autoris\u00e9e de votre compte.<\/p>\n<p>Vous ne devez pas utiliser le compte d'une autre personne pour acc\u00e9der \u00e0 notre site web institutionnel, sauf si vous avez l'autorisation expresse de cette personne.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"container fade-in-top\">\n<div>\n<h4 class=\"content-title-color-var\">6. Donn\u00e9es de connexion de l'utilisateur<\/h4>\n<p>&nbsp;<\/p>\n<p>Si vous cr\u00e9ez un compte sur notre site web en tant qu'employ\u00e9 ou en tant que partenaire s\u00e9lectionn\u00e9, il vous sera demand\u00e9 de choisir un nom d'utilisateur (courriel) et un mot de passe.<\/p>\n<p>Votre identifiant ne doit pas \u00eatre susceptible d'induire en erreur et doit \u00eatre conforme aux r\u00e8gles de contenu \u00e9nonc\u00e9es dans la section ci-dessous ; vous ne devez pas utiliser votre compte ou votre identifiant pour usurper l'identit\u00e9 d'une personne ou en relation avec une telle usurpation.<\/p>\n<p>Vous devez garder votre mot de passe confidentiel.<\/p>\n<p>Vous devez nous informer imm\u00e9diatement par \u00e9crit de toute divulgation de votre mot de passe.<\/p>\n<p>En tant qu'employ\u00e9 ou partenaire, vous \u00eates responsable de toute activit\u00e9 sur notre site web d'entreprise r\u00e9sultant d'un manquement \u00e0 la confidentialit\u00e9 de votre mot de passe, et pouvez \u00eatre tenu responsable de toute perte r\u00e9sultant d'un tel manquement.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"container fade-in-top\">\n<div>\n<h4 class=\"content-title-color-var\">7. Annulation et suspension du compte<\/h4>\n<p>&nbsp;<\/p>\n<p>Nous pouvons :<\/p>\n<ol>\n<li>\n<ol start=\"1\">\n<li>suspendre votre compte ;<\/li>\n<li>annuler votre compte ; et\/ou<\/li>\n<li>modifier les d\u00e9tails de votre compte,<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p>\u00e0 tout moment, \u00e0 notre seule discr\u00e9tion, sans pr\u00e9avis ni explication.<\/p>\n<p>Vous pouvez r\u00e9silier votre compte sur le site web de notre entreprise en nous envoyant un message \u00e0 l'adresse suivante\u00a0<a href=\"mailto:privacy@fischerconnectors.ch\">privacy@fischerconnectors.ch<\/a><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"container fade-in-top\">\n<div>\n<h4 class=\"content-title-color-var\">8. Signaler un abus<\/h4>\n<p>&nbsp;<\/p>\n<p>Si vous avez connaissance de mat\u00e9riel ou d'activit\u00e9s illicites sur nos sites web, ou de mat\u00e9riel ou d'activit\u00e9s qui enfreignent les pr\u00e9sentes conditions g\u00e9n\u00e9rales, veuillez nous en informer.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"container fade-in-top\">\n<div>\n<h4 class=\"content-title-color-var\">9. Garanties limit\u00e9es<\/h4>\n<p>&nbsp;<\/p>\n<p>Nous ne garantissons pas et ne repr\u00e9sentons pas :<\/p>\n<ol>\n<li>\n<ol start=\"1\">\n<li>l'exhaustivit\u00e9 ou l'exactitude des informations publi\u00e9es sur nos sites web ;<\/li>\n<li>que le contenu des sites web est \u00e0 jour ; ou<\/li>\n<li>que les sites web ou tout service sur les sites web resteront disponibles.<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p>Nous nous r\u00e9servons le droit d'interrompre ou de modifier tout ou partie des services de nos sites web, et de cesser de publier nos sites web, \u00e0 tout moment et \u00e0 notre seule discr\u00e9tion, sans pr\u00e9avis ni explication ; et sauf disposition contraire expresse dans les pr\u00e9sentes conditions g\u00e9n\u00e9rales, vous n'aurez droit \u00e0 aucune compensation ou autre paiement en cas d'interruption ou de modification des services de nos sites web, ou si nous cessons de publier les sites web.<\/p>\n<p>Dans toute la mesure permise par la loi applicable et sous r\u00e9serve de la section ci-dessus, nous excluons toutes les d\u00e9clarations et garanties relatives \u00e0 l'objet des pr\u00e9sentes conditions g\u00e9n\u00e9rales, \u00e0 nos sites web et \u00e0 l'utilisation de nos sites web.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"container fade-in-top\">\n<div>\n<h4 class=\"content-title-color-var\">10. Limitations et exclusions de responsabilit\u00e9<\/h4>\n<p>&nbsp;<\/p>\n<p>Aucune disposition des pr\u00e9sentes conditions g\u00e9n\u00e9rales n'est applicable :<\/p>\n<ol>\n<li>\n<ol start=\"1\">\n<li>limiter ou exclure toute responsabilit\u00e9 en cas de d\u00e9c\u00e8s ou de dommages corporels r\u00e9sultant d'une n\u00e9gligence ;<\/li>\n<li>limiter ou exclure toute responsabilit\u00e9 en cas de fraude ou de d\u00e9claration frauduleuse ;<\/li>\n<li>limiter toute responsabilit\u00e9 d'une mani\u00e8re qui n'est pas autoris\u00e9e par le droit applicable ; ou<\/li>\n<li>exclure toute responsabilit\u00e9 qui ne peut \u00eatre exclue en vertu du droit applicable.<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p>Les limitations et exclusions de responsabilit\u00e9 \u00e9nonc\u00e9es dans la pr\u00e9sente section et ailleurs dans les pr\u00e9sentes conditions g\u00e9n\u00e9rales :<\/p>\n<ol>\n<li>\n<ol start=\"1\">\n<li>sont soumis \u00e0 la section ci-dessus ; et<\/li>\n<li>r\u00e9gissent toutes les responsabilit\u00e9s d\u00e9coulant des pr\u00e9sentes conditions g\u00e9n\u00e9rales ou li\u00e9es \u00e0 l'objet des pr\u00e9sentes conditions g\u00e9n\u00e9rales, y compris les responsabilit\u00e9s contractuelles, d\u00e9lictuelles (y compris la n\u00e9gligence) et pour violation d'une obligation l\u00e9gale, sauf dans la mesure o\u00f9 les pr\u00e9sentes conditions g\u00e9n\u00e9rales en disposent autrement de mani\u00e8re expresse.<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p>Dans la mesure o\u00f9 nos sites web et les informations et services qu'ils contiennent sont fournis gratuitement, nous ne sommes pas responsables des pertes ou dommages de quelque nature que ce soit.<\/p>\n<p>Nous ne serons pas responsables envers vous des pertes r\u00e9sultant d'un ou de plusieurs \u00e9v\u00e9nements \u00e9chappant \u00e0 notre contr\u00f4le raisonnable.<\/p>\n<p>Nous ne serons pas responsables envers vous des pertes commerciales, y compris (sans limitation) la perte ou l'endommagement de b\u00e9n\u00e9fices, de revenus, de recettes, d'utilisation, de production, d'\u00e9conomies anticip\u00e9es, d'affaires, de contrats, d'opportunit\u00e9s commerciales ou de fonds de commerce.<\/p>\n<p>Nous ne serons pas responsables envers vous de la perte ou de la corruption de toute donn\u00e9e, base de donn\u00e9es ou logiciel.<\/p>\n<p>Nous ne serons pas responsables envers vous de toute perte ou de tout dommage sp\u00e9cial, indirect ou cons\u00e9cutif.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"container fade-in-top\">\n<div>\n<h4 class=\"content-title-color-var\">11. Indemnisation<\/h4>\n<p>&nbsp;<\/p>\n<p>Par la pr\u00e9sente, vous nous indemnisez et vous vous engagez \u00e0 nous indemniser pour l'ensemble des pertes, dommages, co\u00fbts, responsabilit\u00e9s et d\u00e9penses (y compris, mais sans s'y limiter, les frais de justice et tout montant pay\u00e9 par nous \u00e0 un tiers en r\u00e8glement d'une r\u00e9clamation ou d'un litige) encourus ou subis par nous et d\u00e9coulant directement ou indirectement de votre utilisation de notre site web ou de toute violation par vous de l'une des dispositions des pr\u00e9sentes conditions g\u00e9n\u00e9rales d'utilisation.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"container fade-in-top\">\n<div>\n<h4 class=\"content-title-color-var\">12. Violation des pr\u00e9sentes conditions g\u00e9n\u00e9rales<\/h4>\n<p>&nbsp;<\/p>\n<p>Sans pr\u00e9judice de nos autres droits en vertu des pr\u00e9sentes conditions g\u00e9n\u00e9rales, si vous enfreignez les pr\u00e9sentes conditions g\u00e9n\u00e9rales de quelque mani\u00e8re que ce soit, ou si nous soup\u00e7onnons raisonnablement que vous avez enfreint les pr\u00e9sentes conditions g\u00e9n\u00e9rales de quelque mani\u00e8re que ce soit, nous pouvons.. :<\/p>\n<ol>\n<li>\n<ol start=\"1\">\n<li>vous envoyer un ou plusieurs avertissements formels ;<\/li>\n<li>suspendre temporairement votre acc\u00e8s au site web de l'entreprise ;<\/li>\n<li>vous interdire d\u00e9finitivement l'acc\u00e8s \u00e0 notre site Internet ;<\/li>\n<li>emp\u00eacher les ordinateurs utilisant votre adresse IP d'acc\u00e9der \u00e0 notre site web ;<\/li>\n<li>intenter une action en justice contre vous, que ce soit pour rupture de contrat ou autre ; et\/ou<\/li>\n<li>suspendre ou supprimer votre compte sur notre site web institutionnel.<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p>Si nous suspendons, interdisons ou bloquons votre acc\u00e8s \u00e0 nos sites web ou \u00e0 une partie de ceux-ci, vous ne devez prendre aucune mesure pour contourner cette suspension, cette interdiction ou ce blocage (y compris, sans s'y limiter, la cr\u00e9ation et\/ou l'utilisation d'un compte diff\u00e9rent).<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"container fade-in-top\">\n<div>\n<h4 class=\"content-title-color-var\">13. Sites web de tiers<\/h4>\n<p>&nbsp;<\/p>\n<p>Notre site web comprend des hyperliens vers d'autres sites web d\u00e9tenus et exploit\u00e9s par des tiers ; ces hyperliens ne sont pas des recommandations.<\/p>\n<p>Nous n'avons aucun contr\u00f4le sur les sites web de tiers et leur contenu et, sous r\u00e9serve de la section ci-dessus, nous n'acceptons aucune responsabilit\u00e9 pour eux ou pour toute perte ou tout dommage pouvant r\u00e9sulter de leur utilisation.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"container fade-in-top\">\n<div>\n<h4 class=\"content-title-color-var\">14. Marques d\u00e9pos\u00e9es<\/h4>\n<p>&nbsp;<\/p>\n<p>Fischer AluLite\u2122, Fischer UltiMate\u2122, Fischer MiniMax\u2122, Fischer Freedom\u2122 , LP360\u2122, nos logos et nos autres marques d\u00e9pos\u00e9es et non d\u00e9pos\u00e9es sont des marques commerciales nous appartenant ; nous ne donnons aucune autorisation pour l'utilisation de ces marques, et une telle utilisation peut constituer une violation de nos droits.<\/p>\n<p>Les marques d\u00e9pos\u00e9es et non d\u00e9pos\u00e9es de tiers ou les marques de service figurant sur notre site web sont la propri\u00e9t\u00e9 de leurs d\u00e9tenteurs respectifs et, sauf indication contraire dans les pr\u00e9sentes conditions g\u00e9n\u00e9rales, nous n'approuvons aucun des d\u00e9tenteurs de ces droits et n'y sommes pas affili\u00e9s, de sorte que nous ne pouvons accorder aucune licence pour l'exercice de ces droits.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"container fade-in-top\">\n<div>\n<h4 class=\"content-title-color-var\">15. Variation<\/h4>\n<p>&nbsp;<\/p>\n<p>Nous pouvons r\u00e9viser ces termes et conditions de temps \u00e0 autre.<\/p>\n<p>Les conditions g\u00e9n\u00e9rales r\u00e9vis\u00e9es s'appliquent \u00e0 l'utilisation de nos sites web \u00e0 compter de la date de publication des conditions g\u00e9n\u00e9rales r\u00e9vis\u00e9es sur les sites web, et vous renoncez par la pr\u00e9sente \u00e0 tout droit que vous pourriez avoir par ailleurs d'\u00eatre inform\u00e9 des r\u00e9visions de ces conditions g\u00e9n\u00e9rales ou d'y consentir.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"container fade-in-top\">\n<div>\n<h4 class=\"content-title-color-var\">16. Affectation<\/h4>\n<p>&nbsp;<\/p>\n<p>Vous acceptez par la pr\u00e9sente que nous puissions c\u00e9der, transf\u00e9rer, sous-traiter ou traiter de toute autre mani\u00e8re nos droits et\/ou obligations en vertu des pr\u00e9sentes conditions g\u00e9n\u00e9rales.<\/p>\n<p>Vous ne pouvez pas, sans notre consentement \u00e9crit pr\u00e9alable, c\u00e9der, transf\u00e9rer, sous-traiter ou traiter de toute autre mani\u00e8re l'un quelconque de vos droits et\/ou obligations en vertu des pr\u00e9sentes conditions g\u00e9n\u00e9rales.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"container fade-in-top\">\n<div>\n<h4 class=\"content-title-color-var\">17. Divisibilit\u00e9<\/h4>\n<p>&nbsp;<\/p>\n<p>Si une disposition des pr\u00e9sentes conditions g\u00e9n\u00e9rales est jug\u00e9e ill\u00e9gale et\/ou inapplicable par un tribunal ou une autre autorit\u00e9 comp\u00e9tente, les autres dispositions resteront en vigueur.<\/p>\n<p>Si une disposition ill\u00e9gale et\/ou inapplicable des pr\u00e9sentes conditions g\u00e9n\u00e9rales \u00e9tait l\u00e9gale ou applicable si une partie \u00e9tait supprim\u00e9e, cette partie serait consid\u00e9r\u00e9e comme supprim\u00e9e et le reste de la disposition resterait en vigueur.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"container fade-in-top\">\n<div>\n<h4 class=\"content-title-color-var\">18. Int\u00e9gralit\u00e9 de l'accord<\/h4>\n<p>&nbsp;<\/p>\n<p>Sous r\u00e9serve de l'article 10, les pr\u00e9sentes conditions d'utilisation, ainsi que nos\u00a0<a href=\"https:\/\/www.fischerconnectors.com\/switzerland-en\/en\/privacy-policy\" data-setcurrentdomainvariant=\"true\">politique de confidentialit\u00e9<\/a>\u00a0et\u00a0<a href=\"https:\/\/www.fischerconnectors.com\/switzerland-en\/en\/cookies-policy\" data-setcurrentdomainvariant=\"true\">politique en mati\u00e8re de cookies<\/a>, L'utilisation de notre site Internet constitue l'int\u00e9gralit\u00e9 de l'accord entre vous et nous en ce qui concerne l'utilisation de nos sites Internet et remplace tous les accords ant\u00e9rieurs entre vous et nous en ce qui concerne l'utilisation de nos sites Internet.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"container fade-in-top\">\n<div>\n<h4 class=\"content-title-color-var\">19. Droit et juridiction<\/h4>\n<p>&nbsp;<\/p>\n<p>Les pr\u00e9sentes conditions sont r\u00e9gies et interpr\u00e9t\u00e9es conform\u00e9ment au droit suisse.<\/p>\n<p>Tout litige relatif aux pr\u00e9sentes conditions g\u00e9n\u00e9rales sera soumis \u00e0 la comp\u00e9tence exclusive des tribunaux suisses.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"container fade-in-top\">\n<div>\n<h4 class=\"content-title-color-var\">20. Nos coordonn\u00e9es<\/h4>\n<p>&nbsp;<\/p>\n<p>Ces sites Internet sont d\u00e9tenus et exploit\u00e9s par Fischer Connectors SA.<\/p>\n<p>Nous sommes enregistr\u00e9s en Suisse sous le num\u00e9ro CHE-109.869.648 et notre si\u00e8ge social est situ\u00e9 \u00e0 1162 St-Prex, Suisse.<\/p>\n<p>Notre si\u00e8ge social est situ\u00e9 au Chemin du Glapin 20, 1162 St-Prex, Suisse.<\/p>\n<p>Vous pouvez nous contacter :<\/p>\n<ol>\n<li>\n<ol start=\"1\">\n<li>par courrier, \u00e0 l'adresse postale indiqu\u00e9e ci-dessus ;<\/li>\n<li>en utilisant le formulaire de contact de notre site web ;<\/li>\n<li>par t\u00e9l\u00e9phone, au +41 (0)21 800 95 95 ; ou<\/li>\n<li>par courrier \u00e9lectronique, en utilisant\u00a0<a href=\"mailto:mail@fischerconnectors.ch\">mail@fischerconnectors.ch<\/a>.<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<div class=\"container fade-in-top\">\n<div class=\"w-full\">\n<p>St-Prex, Fischer Connectors SA, 24.05.2018<\/p>\n<\/div>\n<\/div>\n<\/div><\/div>        <\/div>\r\n        <div class=\"row justify-content-center\">\r\n            <div class=\"col-lg-11\">\r\n                <div class=\"line\"><\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-764","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Terms and Conditions - WEARIN&#039;<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wearin.tech\/fr\/terms-and-conditions\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Terms and Conditions - WEARIN&#039;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wearin.tech\/fr\/terms-and-conditions\/\" \/>\n<meta property=\"og:site_name\" content=\"WEARIN&#039;\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-05T13:28:18+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wearin.tech\\\/terms-and-conditions\\\/\",\"url\":\"https:\\\/\\\/wearin.tech\\\/terms-and-conditions\\\/\",\"name\":\"Terms and Conditions - WEARIN&#039;\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wearin.tech\\\/#website\"},\"datePublished\":\"2025-10-21T16:10:42+00:00\",\"dateModified\":\"2025-11-05T13:28:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wearin.tech\\\/terms-and-conditions\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wearin.tech\\\/terms-and-conditions\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wearin.tech\\\/terms-and-conditions\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wearin.tech\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Terms and Conditions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wearin.tech\\\/#website\",\"url\":\"https:\\\/\\\/wearin.tech\\\/\",\"name\":\"WEARIN'\",\"description\":\"Smart safety IoT platform for the connected workers\",\"publisher\":{\"@id\":\"https:\\\/\\\/wearin.tech\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wearin.tech\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wearin.tech\\\/#organization\",\"name\":\"WEARIN'\",\"url\":\"https:\\\/\\\/wearin.tech\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/wearin.tech\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wearin.tech\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Wearin_Part_of_Conextivity_Color_Center.png\",\"contentUrl\":\"https:\\\/\\\/wearin.tech\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Wearin_Part_of_Conextivity_Color_Center.png\",\"width\":1289,\"height\":500,\"caption\":\"WEARIN'\"},\"image\":{\"@id\":\"https:\\\/\\\/wearin.tech\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/ch.linkedin.com\\\/company\\\/wearin\",\"https:\\\/\\\/youtube.com\\\/@wearin_conextivitygroup\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Terms and Conditions - WEARIN&#039;","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wearin.tech\/fr\/terms-and-conditions\/","og_locale":"fr_FR","og_type":"article","og_title":"Terms and Conditions - WEARIN&#039;","og_url":"https:\/\/wearin.tech\/fr\/terms-and-conditions\/","og_site_name":"WEARIN&#039;","article_modified_time":"2025-11-05T13:28:18+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wearin.tech\/terms-and-conditions\/","url":"https:\/\/wearin.tech\/terms-and-conditions\/","name":"Terms and Conditions - WEARIN&#039;","isPartOf":{"@id":"https:\/\/wearin.tech\/#website"},"datePublished":"2025-10-21T16:10:42+00:00","dateModified":"2025-11-05T13:28:18+00:00","breadcrumb":{"@id":"https:\/\/wearin.tech\/terms-and-conditions\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wearin.tech\/terms-and-conditions\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wearin.tech\/terms-and-conditions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wearin.tech\/"},{"@type":"ListItem","position":2,"name":"Terms and Conditions"}]},{"@type":"WebSite","@id":"https:\/\/wearin.tech\/#website","url":"https:\/\/wearin.tech\/","name":"PORTANT'","description":"Plateforme IoT de s\u00e9curit\u00e9 intelligente pour les travailleurs connect\u00e9s","publisher":{"@id":"https:\/\/wearin.tech\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wearin.tech\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/wearin.tech\/#organization","name":"PORTANT'","url":"https:\/\/wearin.tech\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wearin.tech\/#\/schema\/logo\/image\/","url":"https:\/\/wearin.tech\/wp-content\/uploads\/2025\/12\/Wearin_Part_of_Conextivity_Color_Center.png","contentUrl":"https:\/\/wearin.tech\/wp-content\/uploads\/2025\/12\/Wearin_Part_of_Conextivity_Color_Center.png","width":1289,"height":500,"caption":"WEARIN'"},"image":{"@id":"https:\/\/wearin.tech\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/ch.linkedin.com\/company\/wearin","https:\/\/youtube.com\/@wearin_conextivitygroup"]}]}},"_links":{"self":[{"href":"https:\/\/wearin.tech\/fr\/wp-json\/wp\/v2\/pages\/764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wearin.tech\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wearin.tech\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wearin.tech\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wearin.tech\/fr\/wp-json\/wp\/v2\/comments?post=764"}],"version-history":[{"count":10,"href":"https:\/\/wearin.tech\/fr\/wp-json\/wp\/v2\/pages\/764\/revisions"}],"predecessor-version":[{"id":1470,"href":"https:\/\/wearin.tech\/fr\/wp-json\/wp\/v2\/pages\/764\/revisions\/1470"}],"wp:attachment":[{"href":"https:\/\/wearin.tech\/fr\/wp-json\/wp\/v2\/media?parent=764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}